{"id":35000,"date":"2017-11-25T18:18:36","date_gmt":"2017-11-25T18:18:36","guid":{"rendered":"http:\/\/hqcosmetique.com\/?post_type=product&#038;p=35000"},"modified":"2021-03-15T11:56:20","modified_gmt":"2021-03-15T11:56:20","slug":"lozione-peeling-rigenerante","status":"publish","type":"product","link":"http:\/\/hqcosmetique.com\/it\/prodotto\/lozione-peeling-rigenerante\/","title":{"rendered":"LOZIONE PEELING RIGENERANTE"},"content":{"rendered":"<p>RIGENERA, LEVIGA E RESTITUISCE SPLENDORE<\/p>\n<p>La lozione peeling elimina le impurit\u00e0 e attiva il rinnovamento cellulare contribuendo a rivelare un incarnato perfetto. Elimina delicatamente e in maniera non abrasiva le cellule morte e favorisce la rigenerazione della pelle, migliorandone la texture e la luminosit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<h2>LOZIONE PEELING RIGENERANTE<\/h2>\n<p>alle cellule native dei Kiwi Arguta e Cardo<\/p>\n","protected":false},"featured_media":32545,"comment_status":"open","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"http:\/\/hqcosmetique.com\/it\/wp-json\/wp\/v2\/product\/35000"}],"collection":[{"href":"http:\/\/hqcosmetique.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/hqcosmetique.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"http:\/\/hqcosmetique.com\/it\/wp-json\/wp\/v2\/comments?post=35000"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hqcosmetique.com\/it\/wp-json\/wp\/v2\/media\/32545"}],"wp:attachment":[{"href":"http:\/\/hqcosmetique.com\/it\/wp-json\/wp\/v2\/media?parent=35000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}